












{"id":8786,"date":"2018-06-01T09:46:13","date_gmt":"2018-06-01T07:46:13","guid":{"rendered":"https:\/\/www.tommasi.it\/negozio\/senza%20categoria\/co4020-1-murano-glass-necklace-gold-leaf\/"},"modified":"2020-02-10T12:34:46","modified_gmt":"2020-02-10T11:34:46","slug":"co4020-1-murano-glass-necklace-gold-leaf","status":"publish","type":"product","link":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/","title":{"rendered":"CO4020-1 Murano Glass Necklace gold leaf"},"content":{"rendered":"<p>Murano Glass Necklace 10mm gold leaf 24kt red heart,45 cm,gift box and warranty card Tommasi Murano Glass included<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Murano Glass Necklace 10mm gold leaf 24kt red heart,45 cm,gift box and warranty card Tommasi Murano Glass included<\/p>\n","protected":false},"featured_media":8784,"template":"","meta":[],"product_cat":[25],"product_tag":[638,650],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry\" \/>\n<meta property=\"og:description\" content=\"Murano Glass Necklace 10mm gold leaf 24kt red heart,45 cm,gift box and warranty card Tommasi Murano Glass included\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/\" \/>\n<meta property=\"og:site_name\" content=\"Tommasi Murano - Glass Jewelry\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-10T11:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/\",\"url\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/\",\"name\":\"CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry\",\"isPartOf\":{\"@id\":\"https:\/\/www.tommasi.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg\",\"datePublished\":\"2018-06-01T07:46:13+00:00\",\"dateModified\":\"2020-02-10T11:34:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage\",\"url\":\"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg\",\"contentUrl\":\"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg\",\"width\":734,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tommasi.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.tommasi.it\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CO4020-1 Murano Glass Necklace gold leaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tommasi.it\/en\/#website\",\"url\":\"https:\/\/www.tommasi.it\/en\/\",\"name\":\"Tommasi Murano - Glass Jewelry\",\"description\":\"Murano Glass\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tommasi.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/","og_locale":"en_US","og_type":"article","og_title":"CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry","og_description":"Murano Glass Necklace 10mm gold leaf 24kt red heart,45 cm,gift box and warranty card Tommasi Murano Glass included","og_url":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/","og_site_name":"Tommasi Murano - Glass Jewelry","article_modified_time":"2020-02-10T11:34:46+00:00","og_image":[{"width":734,"height":550,"url":"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/","url":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/","name":"CO4020-1 Murano Glass Necklace gold leaf - Tommasi Murano - Glass Jewelry","isPartOf":{"@id":"https:\/\/www.tommasi.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage"},"image":{"@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg","datePublished":"2018-06-01T07:46:13+00:00","dateModified":"2020-02-10T11:34:46+00:00","breadcrumb":{"@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#primaryimage","url":"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg","contentUrl":"https:\/\/www.tommasi.it\/wp-content\/uploads\/2018\/06\/CO4020_1.jpg","width":734,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.tommasi.it\/en\/negozio\/jewelry\/co4020-1-murano-glass-necklace-gold-leaf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tommasi.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.tommasi.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"CO4020-1 Murano Glass Necklace gold leaf"}]},{"@type":"WebSite","@id":"https:\/\/www.tommasi.it\/en\/#website","url":"https:\/\/www.tommasi.it\/en\/","name":"Tommasi Murano - Glass Jewelry","description":"Murano Glass","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tommasi.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/product\/8786"}],"collection":[{"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/media\/8784"}],"wp:attachment":[{"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/media?parent=8786"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/product_cat?post=8786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tommasi.it\/en\/wp-json\/wp\/v2\/product_tag?post=8786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}